{"id":1440,"date":"2017-02-02T11:25:03","date_gmt":"2017-02-02T10:25:03","guid":{"rendered":"http:\/\/www.godaddy.dikayo.com\/?p=1440"},"modified":"2017-02-02T11:25:03","modified_gmt":"2017-02-02T10:25:03","slug":"dios-es-neutral-no-creo-que-para-el-exista-lo-bueno-y-lo-malo","status":"publish","type":"post","link":"https:\/\/dikayo.com\/es\/dios-es-neutral-no-creo-que-para-el-exista-lo-bueno-y-lo-malo\/","title":{"rendered":"\u00abDios es neutral. No creo que para \u00c9l exista lo bueno y lo malo.\u00bb"},"content":{"rendered":"<div class=\"resp-video-center\" style=\"width: 100%;\"><div class=\"resp-video-wrapper size-16-9\"><iframe title=\"Jimena: una mexicana sincera.\" src=\"https:\/\/www.youtube.com\/embed\/m9G4TIqwzSU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div>\n<h4>Jimena es una joven muy inteligente que ve la creaci\u00f3n y entiende que hay un Creador. Sin embargo, ella no piensa que Dios tenga un sentido del bien y del mal, sino neutro.<\/h4>\n<h4>Observa c\u00f3mo ella est\u00e1 dispuesta a escuchar y reflexionar.<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1437\" src=\"http:\/\/www.godaddy.dikayo.com\/wp-content\/uploads\/2017\/02\/IMG_8148-300x225.jpg\" alt=\"IMG_8148\" width=\"300\" height=\"225\" srcset=\"https:\/\/dikayo.com\/wp-content\/uploads\/2017\/02\/IMG_8148-300x225.jpg 300w, https:\/\/dikayo.com\/wp-content\/uploads\/2017\/02\/IMG_8148.jpg 688w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jimena es una joven muy inteligente que ve la creaci\u00f3n y entiende que hay un Creador. Sin embargo, ella no piensa que Dios tenga un sentido del bien y del mal, sino neutro.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-1440","post","type-post","status-publish","format-standard","hentry","category-viajar"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/posts\/1440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/comments?post=1440"}],"version-history":[{"count":1,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/posts\/1440\/revisions"}],"predecessor-version":[{"id":1441,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/posts\/1440\/revisions\/1441"}],"wp:attachment":[{"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/media?parent=1440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/categories?post=1440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dikayo.com\/es\/wp-json\/wp\/v2\/tags?post=1440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}