{"id":615,"date":"2014-07-19T13:56:48","date_gmt":"2014-07-19T11:56:48","guid":{"rendered":"http:\/\/www.godaddy.dikayo.com\/?p=615"},"modified":"2014-07-19T14:47:00","modified_gmt":"2014-07-19T12:47:00","slug":"29-pourquoi-les-dinosaures-ne-sont-ils-pas-mentionnes-dans-la-bible","status":"publish","type":"post","link":"https:\/\/dikayo.com\/fr\/29-pourquoi-les-dinosaures-ne-sont-ils-pas-mentionnes-dans-la-bible\/","title":{"rendered":"29. \u00ab\u00a0Pourquoi les dinosaures ne sont-ils pas mentionn\u00e9s dans la Bible?\u00a0\u00bb"},"content":{"rendered":"<div id=\"attachment_616\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-616\" class=\"wp-image-616 size-medium\" src=\"http:\/\/www.godaddy.dikayo.com\/wp-content\/uploads\/2014\/07\/622792_88155825-300x225.jpg\" alt=\"622792_88155825\" width=\"300\" height=\"225\" srcset=\"https:\/\/dikayo.com\/wp-content\/uploads\/2014\/07\/622792_88155825-300x225.jpg 300w, https:\/\/dikayo.com\/wp-content\/uploads\/2014\/07\/622792_88155825-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-616\" class=\"wp-caption-text\">Photo: Janusz Michalczuk<\/p><\/div>\n<p><i>En tout premier<\/i>, nous ne devrions pas nous attendre \u00e0 trouver le mot <i>dinosaure<\/i> dans la Bible. Le terme ne fut pas invent\u00e9 avant qu&rsquo;un fameux pal\u00e9ontologiste, Sir Richard Owen, leur donne ce nom en 1841 &#8212; pr\u00e8s de dix huit si\u00e8cles apr\u00e8s que le Nouveau Testament ne soit achev\u00e9.<\/p>\n<p><i>Deuxi\u00e8mement, <\/i>rien que parce qu&rsquo;une cr\u00e9ature n&rsquo;est pas mentionn\u00e9e dans la Bible ne signifie en aucun cas qu&rsquo;elle n&rsquo;existe pas. Il y a des milliers de cr\u00e9atures qui ne sont pas mentionn\u00e9es sp\u00e9cifiquement dans la Bible: Les girafes, les alligators, les pingouins<span style=\"color: #ff2600;\">\u00a0<\/span>rien que pour en nommer quelques uns.<\/p>\n<p><i>Troisi\u00e8mement,<\/i> La Bible mentionne en r\u00e9alit\u00e9 au moins deux cr\u00e9atures qui pourraient tr\u00e8s bien \u00eatre des dinosaures : B\u00e9h\u00e9moth et L\u00e9viathan. B\u00e9h\u00e9moth est d\u00e9crit comme ayant une queue comme un c\u00e8dre (l&rsquo;arbre) (Job 40:15-19). A propos du L\u00e9viathan, le Seigneur dit \u00e0 Job, \u00ab\u00a0&#8230; A son seul aspect n&rsquo;est-on pas terrass\u00e9? Nul n&rsquo;est assez hardi pour l&rsquo;exciter&#8230; Qui soul\u00e8vera son v\u00eatement? Qui p\u00e9n\u00e8trera entre ses m\u00e2choires et ouvrira la porte de sa gueule? Autour de ses dents habite la terreur. Ses magnifiques et puissantes \u00e9cailles&#8230;\u00a0\u00bb (Job 40:28, 41:1,3-6a). Ecailles? Dents terribles? Si hardi que personne n&rsquo;oserait l&rsquo;exciter? Il est ais\u00e9 de voir pourquoi de nombreux \u00e9rudits bibliques en ont conclu que le L\u00e9viathan aurait pu \u00eatre un dinosaure.<\/p>\n<p><b>Sur\u00a0<\/b><b> <\/b><b>Le DESIGN\u00a0<\/b><\/p>\n<p><b>Intelligent<\/b><\/p>\n<blockquote><p>\u00a0\u00bb Lorsque vous analysez toutes les preuves affirmatives les plus actuelles de la Cosmologie, de la Physique, de l&rsquo;Astronomie, de la Biologie et ainsi de suite&#8230; le proc\u00e8s en faveur d&rsquo;un Designer intelligent devient absolument convaincant.\u00a0\u00bb<\/p><\/blockquote>\n<p><b>Jonathan Wells, Dr.<\/b><\/p>\n<p>Homme de Science, en possession d&rsquo;un Doctorat en Biologie mol\u00e9culaire et cellulaire de U.C. Berkeley et d&rsquo;un Doctorat de Yale University. Interview avec Lee Strobel, <i>\u00ab\u00a0The Case for a Creator\u00a0\u00bb (Le Proc\u00e8s pour un Cr\u00e9ateur)<\/i>, 2004, p:66<\/p>\n<blockquote><p>\u00ab\u00a0Le syst\u00e8me le plus beau du soleil, des plan\u00e8tes et des com\u00e8tes ne pourrait se mettre en marche que par le conseil et la domination d&rsquo;un \u00eatre puissant et intelligent.\u00a0\u00bb<\/p><\/blockquote>\n<p><b>Sir Isaac Newton <\/b>(1642-1727)<\/p>\n<p>Physicien Anglais, Math\u00e9maticien, Astronome, Inventeur, Philosophe et Alchimiste, largement consid\u00e9r\u00e9 comme un des hommes de Science les plus influents de l&rsquo;histoire; \u00ab\u00a0<i>Principia, Book III\u00a0\u00bb<\/i> <i>(Principia, Livre III); <\/i>Cit\u00e9<i> <\/i>dans <i>\u00ab\u00a0Newton&rsquo;s Philosophy of Nature: Selections from his Writings\u00a0\u00bb, (La Philosophie de la Nature de Newton: S\u00e9lections de ses Ecrits),<\/i>1953, p:42<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous ne devrions pas nous attendre \u00e0 trouver le mot dinosaure dans la Bible. Le terme ne fut pas invent\u00e9 avant qu&rsquo;un fameux pal\u00e9ontologiste, Sir Richard Owen, leur donne ce nom en 1841.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-615","post","type-post","status-publish","format-standard","hentry","category-40reponses"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/posts\/615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/comments?post=615"}],"version-history":[{"count":2,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/posts\/615\/revisions"}],"predecessor-version":[{"id":648,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/posts\/615\/revisions\/648"}],"wp:attachment":[{"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/media?parent=615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/categories?post=615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dikayo.com\/fr\/wp-json\/wp\/v2\/tags?post=615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}